{"id":4349,"count":1,"description":"","link":"https:\/\/aqartrendeg.com\/en\/tag\/capital-lords-group-company\/","name":"Capital Lords Group company","slug":"capital-lords-group-company","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f - Aqar Trend - Capital Lords Group company<\/title>\n<meta name=\"description\" content=\"\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f &quot;Aqar Trend&quot; .. \u0628\u0648\u0627\u0628\u0629 \u0625\u0639\u0644\u0627\u0645\u064a\u0629 \u0645\u062a\u062e\u0635\u0635\u0629 \u0641\u064a \u0627\u0644\u0634\u0623\u0646 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a \u0628\u0634\u0643\u0644 \u0639\u0627\u0645 \u0648\u0627\u0644\u0639\u0642\u0627\u0631\u064a \u0639\u0644\u064a \u0648\u062c\u0647 \u0627\u0644\u062a\u062d\u062f\u064a\u062f\u060c \u062a\u063a\u0637\u064a \u0643\u0627\u0641\u0629 \u0627\u0644\u0645\u062c\u0627\u0644\u0627\u062a.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capital Lords Group company\" \/>\n<meta property=\"og:description\" content=\"\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f &quot;Aqar Trend&quot; .. \u0628\u0648\u0627\u0628\u0629 \u0625\u0639\u0644\u0627\u0645\u064a\u0629 \u0645\u062a\u062e\u0635\u0635\u0629 \u0641\u064a \u0627\u0644\u0634\u0623\u0646 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a \u0628\u0634\u0643\u0644 \u0639\u0627\u0645 \u0648\u0627\u0644\u0639\u0642\u0627\u0631\u064a \u0639\u0644\u064a \u0648\u062c\u0647 \u0627\u0644\u062a\u062d\u062f\u064a\u062f\u060c \u062a\u063a\u0637\u064a \u0643\u0627\u0641\u0629 \u0627\u0644\u0645\u062c\u0627\u0644\u0627\u062a.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aqartrendeg.com\/en\/tag\/capital-lords-group-company\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f - Aqar Trend\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aqartrendeg.com\/wp-content\/uploads\/2023\/01\/new10-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"298\" \/>\n\t<meta property=\"og:image:height\" content=\"160\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@aqartrendeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/aqartrendeg.com\\\/en\\\/tag\\\/capital-lords-group-company\\\/\",\"url\":\"https:\\\/\\\/aqartrendeg.com\\\/en\\\/tag\\\/capital-lords-group-company\\\/\",\"name\":\"\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f - Aqar Trend - Capital Lords Group company\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aqartrendeg.com\\\/en\\\/#website\"},\"description\":\"\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f \\\"Aqar Trend\\\" .. \u0628\u0648\u0627\u0628\u0629 \u0625\u0639\u0644\u0627\u0645\u064a\u0629 \u0645\u062a\u062e\u0635\u0635\u0629 \u0641\u064a \u0627\u0644\u0634\u0623\u0646 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a \u0628\u0634\u0643\u0644 \u0639\u0627\u0645 \u0648\u0627\u0644\u0639\u0642\u0627\u0631\u064a \u0639\u0644\u064a \u0648\u062c\u0647 \u0627\u0644\u062a\u062d\u062f\u064a\u062f\u060c \u062a\u063a\u0637\u064a \u0643\u0627\u0641\u0629 \u0627\u0644\u0645\u062c\u0627\u0644\u0627\u062a.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aqartrendeg.com\\\/en\\\/tag\\\/capital-lords-group-company\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aqartrendeg.com\\\/en\\\/tag\\\/capital-lords-group-company\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629\",\"item\":\"https:\\\/\\\/aqartrendeg.com\\\/en\\\/tiehome\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capital Lords Group company\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aqartrendeg.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/aqartrendeg.com\\\/en\\\/\",\"name\":\"\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f - Aqar Trend\",\"description\":\"\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f &quot;Aqar Trend&quot; .. \u0628\u0648\u0627\u0628\u0629 \u0625\u0639\u0644\u0627\u0645\u064a\u0629 \u0645\u062a\u062e\u0635\u0635\u0629 \u0641\u064a \u0627\u0644\u0634\u0623\u0646 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a \u0628\u0634\u0643\u0644 \u0639\u0627\u0645 \u0648\u0627\u0644\u0639\u0642\u0627\u0631\u064a \u0639\u0644\u064a \u0648\u062c\u0647 \u0627\u0644\u062a\u062d\u062f\u064a\u062f\u060c \u062a\u063a\u0637\u064a \u0643\u0627\u0641\u0629 \u0627\u0644\u0645\u062c\u0627\u0644\u0627\u062a.\",\"publisher\":{\"@id\":\"https:\\\/\\\/aqartrendeg.com\\\/en\\\/#organization\"},\"alternateName\":\"\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f.. \u0623\u062e\u0628\u0627\u0631\u0643 \u062a\u0631\u064a\u0646\u062f\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aqartrendeg.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aqartrendeg.com\\\/en\\\/#organization\",\"name\":\"\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f\",\"alternateName\":\"aqar trend\",\"url\":\"https:\\\/\\\/aqartrendeg.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aqartrendeg.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aqartrendeg.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/new10-2.png\",\"contentUrl\":\"https:\\\/\\\/aqartrendeg.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/new10-2.png\",\"width\":298,\"height\":160,\"caption\":\"\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f\"},\"image\":{\"@id\":\"https:\\\/\\\/aqartrendeg.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aqartrendeg\",\"https:\\\/\\\/x.com\\\/aqartrendeg\",\"http:\\\/\\\/www.linkedin.com\\\/in\\\/aqartrendeg\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f - Aqar Trend - Capital Lords Group company","description":"\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f \"Aqar Trend\" .. \u0628\u0648\u0627\u0628\u0629 \u0625\u0639\u0644\u0627\u0645\u064a\u0629 \u0645\u062a\u062e\u0635\u0635\u0629 \u0641\u064a \u0627\u0644\u0634\u0623\u0646 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a \u0628\u0634\u0643\u0644 \u0639\u0627\u0645 \u0648\u0627\u0644\u0639\u0642\u0627\u0631\u064a \u0639\u0644\u064a \u0648\u062c\u0647 \u0627\u0644\u062a\u062d\u062f\u064a\u062f\u060c \u062a\u063a\u0637\u064a \u0643\u0627\u0641\u0629 \u0627\u0644\u0645\u062c\u0627\u0644\u0627\u062a.","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Capital Lords Group company","og_description":"\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f \"Aqar Trend\" .. \u0628\u0648\u0627\u0628\u0629 \u0625\u0639\u0644\u0627\u0645\u064a\u0629 \u0645\u062a\u062e\u0635\u0635\u0629 \u0641\u064a \u0627\u0644\u0634\u0623\u0646 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a \u0628\u0634\u0643\u0644 \u0639\u0627\u0645 \u0648\u0627\u0644\u0639\u0642\u0627\u0631\u064a \u0639\u0644\u064a \u0648\u062c\u0647 \u0627\u0644\u062a\u062d\u062f\u064a\u062f\u060c \u062a\u063a\u0637\u064a \u0643\u0627\u0641\u0629 \u0627\u0644\u0645\u062c\u0627\u0644\u0627\u062a.","og_url":"https:\/\/aqartrendeg.com\/en\/tag\/capital-lords-group-company\/","og_site_name":"\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f - Aqar Trend","og_image":[{"width":298,"height":160,"url":"https:\/\/aqartrendeg.com\/wp-content\/uploads\/2023\/01\/new10-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@aqartrendeg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/aqartrendeg.com\/en\/tag\/capital-lords-group-company\/","url":"https:\/\/aqartrendeg.com\/en\/tag\/capital-lords-group-company\/","name":"\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f - Aqar Trend - Capital Lords Group company","isPartOf":{"@id":"https:\/\/aqartrendeg.com\/en\/#website"},"description":"\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f \"Aqar Trend\" .. \u0628\u0648\u0627\u0628\u0629 \u0625\u0639\u0644\u0627\u0645\u064a\u0629 \u0645\u062a\u062e\u0635\u0635\u0629 \u0641\u064a \u0627\u0644\u0634\u0623\u0646 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a \u0628\u0634\u0643\u0644 \u0639\u0627\u0645 \u0648\u0627\u0644\u0639\u0642\u0627\u0631\u064a \u0639\u0644\u064a \u0648\u062c\u0647 \u0627\u0644\u062a\u062d\u062f\u064a\u062f\u060c \u062a\u063a\u0637\u064a \u0643\u0627\u0641\u0629 \u0627\u0644\u0645\u062c\u0627\u0644\u0627\u062a.","breadcrumb":{"@id":"https:\/\/aqartrendeg.com\/en\/tag\/capital-lords-group-company\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/aqartrendeg.com\/en\/tag\/capital-lords-group-company\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629","item":"https:\/\/aqartrendeg.com\/en\/tiehome\/"},{"@type":"ListItem","position":2,"name":"Capital Lords Group company"}]},{"@type":"WebSite","@id":"https:\/\/aqartrendeg.com\/en\/#website","url":"https:\/\/aqartrendeg.com\/en\/","name":"\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f - Aqar Trend","description":"\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f &quot;Aqar Trend&quot; .. \u0628\u0648\u0627\u0628\u0629 \u0625\u0639\u0644\u0627\u0645\u064a\u0629 \u0645\u062a\u062e\u0635\u0635\u0629 \u0641\u064a \u0627\u0644\u0634\u0623\u0646 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a \u0628\u0634\u0643\u0644 \u0639\u0627\u0645 \u0648\u0627\u0644\u0639\u0642\u0627\u0631\u064a \u0639\u0644\u064a \u0648\u062c\u0647 \u0627\u0644\u062a\u062d\u062f\u064a\u062f\u060c \u062a\u063a\u0637\u064a \u0643\u0627\u0641\u0629 \u0627\u0644\u0645\u062c\u0627\u0644\u0627\u062a.","publisher":{"@id":"https:\/\/aqartrendeg.com\/en\/#organization"},"alternateName":"\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f.. \u0623\u062e\u0628\u0627\u0631\u0643 \u062a\u0631\u064a\u0646\u062f","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aqartrendeg.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/aqartrendeg.com\/en\/#organization","name":"\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f","alternateName":"aqar trend","url":"https:\/\/aqartrendeg.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aqartrendeg.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/aqartrendeg.com\/wp-content\/uploads\/2023\/01\/new10-2.png","contentUrl":"https:\/\/aqartrendeg.com\/wp-content\/uploads\/2023\/01\/new10-2.png","width":298,"height":160,"caption":"\u0639\u0642\u0627\u0631 \u062a\u0631\u064a\u0646\u062f"},"image":{"@id":"https:\/\/aqartrendeg.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aqartrendeg","https:\/\/x.com\/aqartrendeg","http:\/\/www.linkedin.com\/in\/aqartrendeg"]}]}},"_links":{"self":[{"href":"https:\/\/aqartrendeg.com\/en\/wp-json\/wp\/v2\/tags\/4349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqartrendeg.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/aqartrendeg.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/aqartrendeg.com\/en\/wp-json\/wp\/v2\/posts?tags=4349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}